{"id":3,"date":"2023-06-10T14:51:20","date_gmt":"2023-06-10T12:51:20","guid":{"rendered":"http:\/\/www.comandstyleconseil.com\/?page_id=3"},"modified":"2023-10-18T13:51:53","modified_gmt":"2023-10-18T11:51:53","slug":"politique-de-confidentialite","status":"publish","type":"page","link":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/","title":{"rendered":"Politique de confidentialit\u00e9"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_heading title=\u00a0\u00bbPolitique de confidentialit\u00e9 de Com&#038;Style\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\"><strong>Com&amp;Style<\/strong> (\u00ab\u00a0<strong>Com&amp;Style\u00a0<\/strong><span>\u00bb<\/span>, \u00ab\u00a0<strong>notre<\/strong>\u00a0\u00bb, \u00ab\u00a0<strong>nous<\/strong>\u00a0\u00bb et \u00ab\u00a0<strong>nos<\/strong>\u00a0\u00bb) et nos partenaires respectent votre vie priv\u00e9e.<\/p>\n<p style=\"font-weight: 400;\">Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet <strong>Com&amp;Style<\/strong>, accessible via l\u2019url <a href=\"https:\/\/www.comandstyleconseil.com\" target=\"_blank\" rel=\"noopener\">https:\/\/www.comandstyleconseil.com<\/a>.<\/p>\n<p style=\"font-weight: 400;\">Le terme \u201cdonn\u00e9es personnelles\u201d d\u00e9signe toute information se rapportant \u00e0 une personne physique et permettant de l\u2019identifier, directement ou indirectement, \u00e0 partir d\u2019une seule donn\u00e9e ou du croisement d\u2019un ensemble de donn\u00e9es.<\/p>\n<p style=\"font-weight: 400;\">L\u2019ensemble des donn\u00e9es personnelles collect\u00e9es sur le pr\u00e9sent site internet sont trait\u00e9es sous la responsabilit\u00e9 de l\u2019entrepreneur Mari\u00e8me MBAYE, immatricul\u00e9 au Registre du Commerce et des Soci\u00e9t\u00e9s de Cr\u00e9teil sous le num\u00e9ro 531758456 et dans le respect de la loi n\u00b0 78-17 du 6 janvier 1978 relative \u00e0 l&rsquo;informatique, aux \ufb01chiers et aux libert\u00e9s, dans sa version actuelle, ainsi que le r\u00e8glement (UE) 2016\/679 du 27 avril 2016 relatif \u00e0 la protection des personnes physiques \u00e0 l&rsquo;\u00e9gard du traitement des donn\u00e9es \u00e0 caract\u00e8re personnel et \u00e0 la libre circulation de ces donn\u00e9es.<\/p>\n<p style=\"font-weight: 400;\">Au sens de la r\u00e9glementation applicable aux donn\u00e9es personnelles, Com&amp;Style est donc responsable de traitement.<\/p>\n<p style=\"font-weight: 400;\">Cette politique de confidentialit\u00e9 d\u00e9crit :<\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li style=\"font-weight: 400;\">Comment Com&amp;Style <span><\/span>utilise vos donn\u00e9es personnelles<\/li>\n<li style=\"font-weight: 400;\">Comment Com&amp;Style partage vos donn\u00e9es personnelles<\/li>\n<li style=\"font-weight: 400;\">Comment Com&amp;Style <span><\/span>prot\u00e8ge vos donn\u00e9es personnelles<\/li>\n<li style=\"font-weight: 400;\">O\u00f9 Com&amp;Style <span><\/span>h\u00e9berge et transf\u00e8re vos donn\u00e9es personnelles<\/li>\n<li style=\"font-weight: 400;\">Comment vous pouvez exercer vos droits relatifs \u00e0 vos donn\u00e9es personnelles<\/li>\n<li style=\"font-weight: 400;\">Les mises \u00e0 jour de la politique de confidentialit\u00e9<\/li>\n<li style=\"font-weight: 400;\">Comment nous contacter<\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbI. Comment Com&#038;Style  utilise vos donn\u00e9es personnelles  \u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Com&amp;Style peut utiliser vos donn\u00e9es personnelles aux fins suivantes :<\/p>\n<ul>\n<li>Cr\u00e9er votre compte client sur le pr\u00e9sent site internet<\/li>\n<li>G\u00e9rer les commandes de produits et\/ou services<\/li>\n<li>Proc\u00e9der aux actions n\u00e9cessaires \u00e0 la gestion de contrats, factures et suivi de la relation client<\/li>\n<li>Publier et g\u00e9rer vos avis et\/ou commentaires laiss\u00e9s sur le site internet<\/li>\n<li>Vous adresser notre newsletter, dans le cas o\u00f9 vous y \u00eates inscrit<\/li>\n<li>R\u00e9pondre \u00e0 votre demande de contact effectu\u00e9e \u00e0 partir de notre site internet<\/li>\n<li>\u00c9tablir un programme de fid\u00e9lit\u00e9<\/li>\n<li>Vous proposer des publicit\u00e9s et un contenu adapt\u00e9<\/li>\n<li>Constituer un fichier d\u2019utilisateurs, de prospects et de clients<\/li>\n<li>\u00c9laborer des statistiques commerciales et de fr\u00e9quentation<\/li>\n<li>G\u00e9rer les impay\u00e9s et litiges \u00e9ventuels<\/li>\n<li>Respecter nos obligations l\u00e9gales<\/li>\n<\/ul>\n<p>\u00a0Les donn\u00e9es collect\u00e9es sont n\u00e9cessaires \u00e0 l\u2019ex\u00e9cution du contrat pass\u00e9 avec Com&amp;Style lorsque vous utilisez notre site internet afin de commander les produits et\/ou services disponibles \u00e0 la vente sur le site.<\/p>\n<p style=\"font-weight: 400;\">Lorsque vous nous fournissez volontairement des donn\u00e9es personnelles, la collecte de vos donn\u00e9es personnelles est fond\u00e9e sur l\u2019int\u00e9r\u00eat l\u00e9gitime suivant : mieux r\u00e9pondre \u00e0 vos demandes d\u2019information.<\/p>\n<p style=\"font-weight: 400;\">Le traitement de vos donn\u00e9es personnelles afin de vous envoyer notre newsletter est, en revanche, bas\u00e9 uniquement sur votre consentement \u00e0 recevoir notre newsletter, que vous pouvez retirer \u00e0 tout moment. Si vous ne consentez pas \u00e0 l\u2019envoi de la newsletter, veuillez noter que cela ne vous emp\u00eachera pas de cr\u00e9er votre compte client et de passer des commandes sur notre site internet.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbII. Comment Com&#038;Style partage vos donn\u00e9es personnelles\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Au sein de <span>Com&amp;Style<\/span>, et au regard de chaque finalit\u00e9 de traitement, les donn\u00e9es personnelles vous concernant sont collect\u00e9es, trait\u00e9es et stock\u00e9es par le personnel habilit\u00e9 de <span>Com&amp;Style<\/span>, uniquement dans le cadre de leurs comp\u00e9tences respectives, et notamment par le service client, le d\u00e9partement marketing et le d\u00e9partement informatique.<\/p>\n<p style=\"font-weight: 400;\">Nous ne partageons pas les donn\u00e9es personnelles avec d\u2019autres entreprises, organisations et personnes, \u00e0 moins que l\u2019une des circonstances suivantes s\u2019applique\u00a0:<\/p>\n<p style=\"font-weight: 400;\"><strong>(1)<\/strong> <strong>Le partage avec consentement pr\u00e9alable<\/strong>\u00a0: apr\u00e8s avoir obtenu votre consentement, Com&amp;Style partagera les informations que vous avez autoris\u00e9es avec les tiers ou cat\u00e9gories de tiers sp\u00e9cifiques renseign\u00e9s \u00e0 l\u2019occasion de la collecte de votre consentement.<\/p>\n<p style=\"font-weight: 400;\"><strong>(2) Le partage avec nos prestataires<\/strong>\u00a0: Com&amp;Style peut \u00e9galement divulguer vos informations \u00e0 des entreprises qui fournissent des services pour nous ou en notre nom. Ces prestataires de services comprennent des entreprises qui proposent des services informatiques tels notamment notre h\u00e9bergeur ou notre prestataire d\u2019envoi d\u2019emails, des services de livraison de nos produits, ou qui proposent des activit\u00e9s marketing pour notre compte. Ces prestataires de services peuvent utiliser vos informations uniquement dans le but de vous fournir des services au nom de Com&amp;Style.<\/p>\n<p style=\"font-weight: 400;\"><strong>(3) En ex\u00e9cution d\u2019une obligation l\u00e9gale, le partage conform\u00e9ment aux lois et \u00e0 la r\u00e9glementation<\/strong>\u00a0: <span>Com&amp;Style<\/span>, peut partager vos informations comme le stipulent les lois et la r\u00e9glementation, afin de r\u00e9soudre les diff\u00e9rends d\u2019ordre juridique, ou comme le stipulent les autorit\u00e9s judiciaires ou administratives en vertu de la loi.<\/p>\n<p style=\"font-weight: 400;\">Com&amp;Style s\u2019assurera de la l\u00e9galit\u00e9 de tout partage des donn\u00e9es personnelles via des clauses de traitement de donn\u00e9es avec les entreprises avec lesquelles vos donn\u00e9es personnelles sont partag\u00e9es, les obligeant \u00e0 se conformer \u00e0 cette politique de confidentialit\u00e9 et \u00e0 prendre les mesures de s\u00e9curit\u00e9 et confidentialit\u00e9 appropri\u00e9es lors du traitement de donn\u00e9es \u00e0 caract\u00e8re personnel.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbIII. Comment Com&#038;Style prot\u00e8ge vos donn\u00e9es personnelles\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Com&amp;Style attache une grande importance \u00e0 la s\u00e9curit\u00e9 de vos donn\u00e9es personnelles et a adopt\u00e9 des pratiques courantes de l&rsquo;industrie afin de prot\u00e9ger vos donn\u00e9es personnelles et d&rsquo;\u00e9viter l&rsquo;acc\u00e8s non autoris\u00e9, la divulgation, l&rsquo;utilisation, la modification, les dommages ou la perte de ces informations.<\/p>\n<p style=\"font-weight: 400;\">Nous avons par ailleurs pris les pr\u00e9cautions utiles afin de pr\u00e9server, par notre h\u00e9bergeur, la s\u00e9curit\u00e9 et la confidentialit\u00e9 des donn\u00e9es, et notamment emp\u00eacher qu\u2019elles ne soient d\u00e9form\u00e9es, endommag\u00e9es ou communiqu\u00e9es \u00e0 des personnes non autoris\u00e9es.<\/p>\n<p style=\"font-weight: 400;\">Com&amp;Style adopte \u00e9galement les mesures organisationnelles suivantes :<\/p>\n<p style=\"font-weight: 400;\">(1) Nous adoptons des mesures raisonnables et r\u00e9alisables afin de veiller \u00e0 ce que les donn\u00e9es personnelles recueillies soient minimes et pertinentes selon ce qui est n\u00e9cessaire, eu \u00e9gard aux fins pour lesquelles elles sont trait\u00e9es.<\/p>\n<p style=\"font-weight: 400;\">(2) Nous conservons vos donn\u00e9es personnelles pendant la dur\u00e9e qui est strictement n\u00e9cessaire au regard de la finalit\u00e9 du traitement, \u00e0 moins que la conservation de vos donn\u00e9es soit requise ou permise par la loi. \u00c0 titre d\u2019exemple, nous conservons les donn\u00e9es li\u00e9es \u00e0 l\u2019ex\u00e9cution de vos commandes pour la dur\u00e9e requise par la loi au titre de conservation des dossiers comptables, \u00e0 savoir au maximum 10 ans \u00e0 compter de l\u2019exercice concern\u00e9.<\/p>\n<p style=\"font-weight: 400;\">(3) Nous d\u00e9ployons les m\u00e9canismes de contr\u00f4le d&rsquo;acc\u00e8s afin de s&rsquo;assurer que seul le personnel habilit\u00e9 peut acc\u00e9der \u00e0 vos donn\u00e9es personnelles.<\/p>\n<p style=\"font-weight: 400;\">En cas de violation des donn\u00e9es personnelles, Com&amp;Style respectera les exigences l\u00e9gales et r\u00e9glementaires applicables \u00e0 la notification des violations de donn\u00e9es personnelles aupr\u00e8s des autorit\u00e9s de contr\u00f4le comp\u00e9tentes et\/ou des personnes concern\u00e9es.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbIV. O\u00f9 Com&#038;Style h\u00e9berge et transf\u00e8re vos donn\u00e9es personnelles\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Vos donn\u00e9es personnelles seront h\u00e9berg\u00e9es au sein des infrastructures d\u2019h\u00e9bergement de notre h\u00e9bergeur, OVH, situ\u00e9 en France.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbV. Comment vous pouvez g\u00e9rer vos droits relatifs \u00e0 vos donn\u00e9es personnelles\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Vous disposez d\u2019un droit d\u2019acc\u00e8s, de rectification, d\u2019effacement, de limitation, d\u2019opposition concernant le traitement de vos donn\u00e9es personnelles ainsi que du droit de d\u00e9finir des directives relatives au sort de vos donn\u00e9es apr\u00e8s votre mort et du droit \u00e0 la portabilit\u00e9 de vos donn\u00e9es personnelles.<\/p>\n<p style=\"font-weight: 400;\">La CNIL d\u00e9finit une donn\u00e9e personnelle comme \u00ab\u00a0toute information se rapportant \u00e0 une personne physique identifi\u00e9e ou identifiable. Mais parce qu\u2019elles concernent des personnes, celles-ci doivent en conserver la ma\u00eetrise\u00a0\u00bb.<span>\u00a0<\/span><\/p>\n<p style=\"font-weight: 400;\">Vous disposez \u00e9galement d\u2019un droit de recours aupr\u00e8s de la Commission Nationale Informatique et Libert\u00e9s pour la France et aupr\u00e8s d\u2019une autorit\u00e9 de contr\u00f4le comp\u00e9tente pour tout autre \u00c9tat membre selon votre r\u00e9sidence habituelle, votre lieu de travail ou le lieu o\u00f9 la violation de vos droits aurait \u00e9t\u00e9 commise si vous estimez que le traitement de vos donn\u00e9es ne respecte pas les textes applicables. Ce recours pourra \u00eatre exerc\u00e9 sans pr\u00e9judice de tout autre recours devant une juridiction administrative ou juridictionnelle qui constitue \u00e9galement un droit dont vous disposez.<\/p>\n<p style=\"font-weight: 400;\">Vous pouvez nous contacter \u00e0 tout moment aux adresses indiqu\u00e9es dans la rubrique \u2018\u2019Comment nous contacter\u2019\u2019 ci-dessous afin d\u2019exercer vos droits en mati\u00e8re de donn\u00e9es personnelles dans les conditions pos\u00e9es par la r\u00e9glementation applicable. Vous devez indiquer quel droit vous entendez exercer ainsi que l\u2019ensemble des pr\u00e9cisions n\u00e9cessaires pour que nous puissions r\u00e9pondre \u00e0 votre demande.<\/p>\n<p style=\"font-weight: 400;\">Ces droits s\u2019exercent dans les conditions pos\u00e9es par la r\u00e9glementation applicable.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Le <strong>droit d\u2019acc\u00e8s<\/strong> signifie que vous pouvez nous demander \u00e0 tout moment de vous indiquer\u00a0si nous traitons des donn\u00e9es personnelles vous concernant et, le cas \u00e9ch\u00e9ant, de vous indiquer quelles sont les donn\u00e9es personnelles concern\u00e9es ainsi que les caract\u00e9ristiques du ou des traitements effectu\u00e9s.<\/li>\n<li>Le <strong>droit de rectification<\/strong> signifie que vous pouvez nous demander la rectification de vos donn\u00e9es personnelles lorsqu\u2019elles sont inexactes. Vous pouvez \u00e9galement demander \u00e0 ce que vos donn\u00e9es personnelles, d\u00e8s lors qu\u2019incompl\u00e8tes, soient compl\u00e9t\u00e9es dans la mesure o\u00f9 cela est pertinent au regard de la finalit\u00e9 du traitement en cause.<\/li>\n<li>Le <strong>droit \u00e0 l\u2019effacement<\/strong> signifie que vous pouvez demander d\u2019effacer vos donn\u00e9es personnelles notamment lorsque\u00a0:\n<ul>\n<li>Leur conservation n\u2019est plus n\u00e9cessaire au regard des finalit\u00e9s pour lesquelles elles ont \u00e9t\u00e9 collect\u00e9es\u00a0;<\/li>\n<li>Vos donn\u00e9es personnelles sont trait\u00e9es sur le fondement de votre consentement, vous souhaitez retirer ce consentement, et il n\u2019existe pas d&rsquo;autre fondement juridique susceptible de justifier le traitement\u00a0;<\/li>\n<li>Vous vous \u00eates oppos\u00e9 au traitement de vos donn\u00e9es personnelles et vous souhaitez en cons\u00e9quence qu\u2019elles soient effac\u00e9es\u00a0;<\/li>\n<li>Vos donn\u00e9es personnelles ont fait l&rsquo;objet d&rsquo;un traitement illicite\u00a0;<\/li>\n<li>Vos donn\u00e9es personnelles doivent \u00eatre effac\u00e9es pour respecter une obligation l\u00e9gale qui est pr\u00e9vue soit par le droit de l&rsquo;Union Europ\u00e9enne soit par le droit fran\u00e7ais.<\/li>\n<\/ul>\n<\/li>\n<li>Le <strong>droit \u00e0 la limitation<\/strong> signifie que vous pouvez nous demander de proc\u00e9der \u00e0 la limitation du traitement de vos donn\u00e9es personnelles\u00a0:\n<ul>\n<li>Lorsque vous contestez l\u2019exactitude de vos donn\u00e9es personnelles pendant une dur\u00e9e nous permettant de v\u00e9rifier l\u2019exactitude de celles-ci\u00a0;<\/li>\n<li>Lorsque suite \u00e0 un traitement \u00e9tabli comme non conforme, vous pr\u00e9f\u00e9rez la limitation du traitement \u00e0 l\u2019effacement complet de vos donn\u00e9es personnelles\u00a0;<\/li>\n<li>Lorsque nous n\u2019avons plus besoin de vos donn\u00e9es personnelles aux fins du traitement mais que celles-ci vous sont encore n\u00e9cessaires pour la constatation, l\u2019exercice ou la d\u00e9fense de droits en justice\u00a0;<\/li>\n<li>Lorsque vous vous \u00eates oppos\u00e9 au traitement de vos donn\u00e9es personnelles et vous souhaitez une limitation du traitement pendant la dur\u00e9e nous permettant de v\u00e9rifier si le motif l\u00e9gitime que vous invoquez se justifie.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>La limitation du traitement signifie que le traitement de vos donn\u00e9es personnelles s\u2019entendra alors du seul stockage de vos donn\u00e9es personnelles correspondantes. Nous n\u2019effectuerons alors plus aucune autre op\u00e9ration sur les donn\u00e9es personnelles consid\u00e9r\u00e9es.<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li>Le <strong>droit d\u2019opposition<\/strong> signifie que vous pouvez vous opposer au traitement de vos donn\u00e9es personnelles, lorsque ce traitement est fond\u00e9 sur la poursuite de l\u2019int\u00e9r\u00eat l\u00e9gitime de Com&amp;Style. Le droit d\u2019opposition s\u2019exerce sous r\u00e9serve de justifier d\u2019un motif l\u00e9gitime tenant \u00e0 votre situation particuli\u00e8re. Nous cesserons alors le traitement en cause sauf s\u2019il existe des motifs l\u00e9gitimes et imp\u00e9rieux en justifiant la poursuite en conformit\u00e9 avec la r\u00e9glementation applicable.<\/li>\n<li>Le <strong>droit de d\u00e9finir des directives relatives au sort de vos donn\u00e9es apr\u00e8s votre mort<\/strong> vous permet de faire conna\u00eetre vos instructions concernant la conservation, l&rsquo;effacement et la communication de vos donn\u00e9es personnelles apr\u00e8s votre d\u00e9c\u00e8s.<\/li>\n<li>Le <strong>droit \u00e0 la portabilit\u00e9<\/strong> signifie que vous pouvez nous demander, dans les conditions pos\u00e9es par la r\u00e9glementation applicable, de recevoir vos donn\u00e9es personnelles dans un format structur\u00e9, couramment utilis\u00e9 et lisible par machine, et de vous les transmettre, ou de nous demander de les transmettre directement \u00e0 un tiers de votre choix lorsque cela est juridiquement et techniquement possible.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"font-weight: 400;\">Lorsque nous traitons vos donn\u00e9es personnelles sur la base de votre consentement, vous disposez enfin de la facult\u00e9 de retirer votre consentement \u00e0 tout moment en vous adressant aux adresses indiqu\u00e9es dans la rubrique \u2019\u2019Comment nous contacter\u2019\u2019 ou en cliquant sur le lien de d\u00e9sabonnement pr\u00e9sent dans chacune de nos communications.<\/p>\n<p style=\"font-weight: 400;\">Toutefois, le retrait de votre consentement ne remet pas en cause la validit\u00e9 du traitement effectu\u00e9 avant ce retrait.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbVI. Les mises \u00e0 jour de cette politique de confidentialit\u00e9\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Com&amp;Style se r\u00e9serve le droit \u00e0 tout moment de modifier ou mettre \u00e0 jour, en tout ou en partie, la pr\u00e9sente politique de confidentialit\u00e9, en raison de la modification de la r\u00e9glementation applicable en mati\u00e8re de protection des donn\u00e9es personnelles ou des traitements de donn\u00e9es effectu\u00e9s.<\/p>\n<p style=\"font-weight: 400;\">Toute modification substantielle de la politique de confidentialit\u00e9 vous sera notifi\u00e9e par e-mail lorsque vous nous avez communiqu\u00e9 une adresse mail valide et sera publi\u00e9e sur le site internet. Nous vous recommandons de prendre r\u00e9guli\u00e8rement connaissance de la pr\u00e9sente politique de confidentialit\u00e9 afin d\u2019avoir une parfaite connaissance de nos engagements en mati\u00e8re de s\u00e9curit\u00e9 et de protection de vos donn\u00e9es personnelles.<\/p>\n<p>[\/et_pb_text][et_pb_heading title=\u00a0\u00bbVII. Comment nous contacter\u00a0\u00bb _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb title_level=\u00a0\u00bbh2&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00a0\u00bb4.22.2&Prime; _module_preset=\u00a0\u00bbdefault\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<p style=\"font-weight: 400;\">Si vous avez des questions, des commentaires ou des suggestions, veuillez nous contacter en visitant la page contactez-nous ou en les soumettant \u00e0 <strong>hello@comandstyleconseil.com<\/strong>.<\/p>\n<p style=\"font-weight: 400;\">Ou par courrier postal \u00e0\u00a025 Rue Charles Gustave Stoskopf, 94000 Cr\u00e9teil, France.<\/p>\n<p style=\"font-weight: 400;\">Si vous n&rsquo;\u00eates pas satisfait de la r\u00e9ponse apport\u00e9e par Com&amp;Style \u00e0 une demande d\u2019exercice de droits conform\u00e9ment \u00e0 l\u2019article V ci-dessus ou que vous souhaitez signaler une atteinte \u00e0 la r\u00e9glementation applicable en mati\u00e8re de protection des donn\u00e9es, vous disposez du droit d\u2019introduire une r\u00e9clamation aupr\u00e8s de la CNIL par courrier (CNIL &#8211; 3 Place de Fontenoy &#8211; TSA 80715 &#8211; 75334 PARIS CEDEX 07) ou sur son site Internet (www.cnil.fr), ou aupr\u00e8s de l&rsquo;autorit\u00e9 de protection des donn\u00e9es du pays dans lequel vous r\u00e9sidez ou travaillez habituellement.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com&amp;Style (\u00ab\u00a0Com&amp;Style\u00a0\u00bb, \u00ab\u00a0notre\u00a0\u00bb, \u00ab\u00a0nous\u00a0\u00bb et \u00ab\u00a0nos\u00a0\u00bb) et nos partenaires respectent votre vie priv\u00e9e. Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&amp;Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com. Le terme \u201cdonn\u00e9es personnelles\u201d d\u00e9signe [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading --><h2>Qui sommes-nous\u00a0?<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>L\u2019adresse de notre site est\u00a0: http:\/\/www.comandstyleconseil.com.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Commentaires<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Quand vous laissez un commentaire sur notre site, les donn\u00e9es inscrites dans le formulaire de commentaire, ainsi que votre adresse IP et l\u2019agent utilisateur de votre navigateur sont collect\u00e9s pour nous aider \u00e0 la d\u00e9tection des commentaires ind\u00e9sirables.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Une cha\u00eene anonymis\u00e9e cr\u00e9\u00e9e \u00e0 partir de votre adresse e-mail (\u00e9galement appel\u00e9e hash) peut \u00eatre envoy\u00e9e au service Gravatar pour v\u00e9rifier si vous utilisez ce dernier. Les clauses de confidentialit\u00e9 du service Gravatar sont disponibles ici\u00a0: https:\/\/automattic.com\/privacy\/. Apr\u00e8s validation de votre commentaire, votre photo de profil sera visible publiquement \u00e0 cot\u00e9 de votre commentaire.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>M\u00e9dias<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous t\u00e9l\u00e9versez des images sur le site, nous vous conseillons d\u2019\u00e9viter de t\u00e9l\u00e9verser des images contenant des donn\u00e9es EXIF de coordonn\u00e9es GPS. Les personnes visitant votre site peuvent t\u00e9l\u00e9charger et extraire des donn\u00e9es de localisation depuis ces images.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Cookies<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous d\u00e9posez un commentaire sur notre site, il vous sera propos\u00e9 d\u2019enregistrer votre nom, adresse e-mail et site dans des cookies. C\u2019est uniquement pour votre confort afin de ne pas avoir \u00e0 saisir ces informations si vous d\u00e9posez un autre commentaire plus tard. Ces cookies expirent au bout d\u2019un an.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Si vous vous rendez sur la page de connexion, un cookie temporaire sera cr\u00e9\u00e9 afin de d\u00e9terminer si votre navigateur accepte les cookies. Il ne contient pas de donn\u00e9es personnelles et sera supprim\u00e9 automatiquement \u00e0 la fermeture de votre navigateur.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Lorsque vous vous connecterez, nous mettrons en place un certain nombre de cookies pour enregistrer vos informations de connexion et vos pr\u00e9f\u00e9rences d\u2019\u00e9cran. La dur\u00e9e de vie d\u2019un cookie de connexion est de deux jours, celle d\u2019un cookie d\u2019option d\u2019\u00e9cran est d\u2019un an. Si vous cochez \u00ab\u00a0Se souvenir de moi\u00a0\u00bb, votre cookie de connexion sera conserv\u00e9 pendant deux semaines. Si vous vous d\u00e9connectez de votre compte, le cookie de connexion sera effac\u00e9.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>En modifiant ou en publiant une publication, un cookie suppl\u00e9mentaire sera enregistr\u00e9 dans votre navigateur. Ce cookie ne comprend aucune donn\u00e9e personnelle. Il indique simplement l\u2019ID de la publication que vous venez de modifier. Il expire au bout d\u2019un jour.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Contenu embarqu\u00e9 depuis d\u2019autres sites<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Les articles de ce site peuvent inclure des contenus int\u00e9gr\u00e9s (par exemple des vid\u00e9os, images, articles\u2026). Le contenu int\u00e9gr\u00e9 depuis d\u2019autres sites se comporte de la m\u00eame mani\u00e8re que si le visiteur se rendait sur cet autre site.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Ces sites web pourraient collecter des donn\u00e9es sur vous, utiliser des cookies, embarquer des outils de suivis tiers, suivre vos interactions avec ces contenus embarqu\u00e9s si vous disposez d\u2019un compte connect\u00e9 sur leur site web.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Utilisation et transmission de vos donn\u00e9es personnelles<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous demandez une r\u00e9initialisation de votre mot de passe, votre adresse IP sera incluse dans l\u2019e-mail de r\u00e9initialisation.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Dur\u00e9es de stockage de vos donn\u00e9es<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous laissez un commentaire, le commentaire et ses m\u00e9tadonn\u00e9es sont conserv\u00e9s ind\u00e9finiment. Cela permet de reconna\u00eetre et approuver automatiquement les commentaires suivants au lieu de les laisser dans la file de mod\u00e9ration.<\/p><!-- \/wp:paragraph --><!-- wp:paragraph --><p>Pour les comptes qui s\u2019inscrivent sur notre site (le cas \u00e9ch\u00e9ant), nous stockons \u00e9galement les donn\u00e9es personnelles indiqu\u00e9es dans leur profil. Tous les comptes peuvent voir, modifier ou supprimer leurs informations personnelles \u00e0 tout moment (\u00e0 l\u2019exception de leur identifiant). Les gestionnaires du site peuvent aussi voir et modifier ces informations.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Les droits que vous avez sur vos donn\u00e9es<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Si vous avez un compte ou si vous avez laiss\u00e9 des commentaires sur le site, vous pouvez demander \u00e0 recevoir un fichier contenant toutes les donn\u00e9es personnelles que nous poss\u00e9dons \u00e0 votre sujet, incluant celles que vous nous avez fournies. Vous pouvez \u00e9galement demander la suppression des donn\u00e9es personnelles vous concernant. Cela ne prend pas en compte les donn\u00e9es stock\u00e9es \u00e0 des fins administratives, l\u00e9gales ou pour des raisons de s\u00e9curit\u00e9.<\/p><!-- \/wp:paragraph --><!-- wp:heading --><h2>Transmission de vos donn\u00e9es personnelles<\/h2><!-- \/wp:heading --><!-- wp:paragraph --><p><strong class=\"privacy-policy-tutorial\">Texte sugg\u00e9r\u00e9\u00a0: <\/strong>Les commentaires des visiteurs peuvent \u00eatre v\u00e9rifi\u00e9s \u00e0 l\u2019aide d\u2019un service automatis\u00e9 de d\u00e9tection des commentaires ind\u00e9sirables.<\/p><!-- \/wp:paragraph -->","_et_gb_content_width":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&amp;Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Com&amp;Style - Mari\u00e8me M. - Conseil en Image &amp; Personal Branding\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 - Com&amp;Style\" \/>\n\t\t<meta property=\"og:description\" content=\"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&amp;Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-10T12:51:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-10-18T11:51:53+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Politique de confidentialit\u00e9 - Com&amp;Style\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&amp;Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.comandstyleconseil.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#listItem\",\"name\":\"Politique de confidentialit\\u00e9\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#listItem\",\"position\":2,\"name\":\"Politique de confidentialit\\u00e9\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/#organization\",\"name\":\"Com&Style\",\"description\":\"Mari\\u00e8me M. - Conseil en Image & Personal Branding\",\"url\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/\",\"telephone\":\"+33675196722\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/logo-def-1.png\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#organizationLogo\",\"width\":1000,\"height\":1000},\"image\":{\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/comandstyle_image\\\/\",\"https:\\\/\\\/www.pinterest.fr\\\/com_and_style_conseil\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/conseilcommunicationetimage\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#webpage\",\"url\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/\",\"name\":\"Politique de confidentialit\\u00e9 - Com&Style\",\"description\":\"Nous vous demandons de bien vouloir lire attentivement la pr\\u00e9sente politique de confidentialit\\u00e9 pour comprendre comment sont collect\\u00e9es, trait\\u00e9es et conserv\\u00e9es vos donn\\u00e9es personnelles lors de votre utilisation du pr\\u00e9sent site internet Com&Style, accessible via l\\u2019url https:\\\/\\\/www.comandstyleconseil.com.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/index.php\\\/politique-de-confidentialite\\\/#breadcrumblist\"},\"datePublished\":\"2023-06-10T14:51:20+02:00\",\"dateModified\":\"2023-10-18T13:51:53+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/#website\",\"url\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/\",\"name\":\"Com&Style\",\"description\":\"Mari\\u00e8me M. - Conseil en Image & Personal Branding\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.comandstyleconseil.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Politique de confidentialit\u00e9 - Com&Style","description":"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.","canonical_url":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.comandstyleconseil.com#listItem","position":1,"name":"Home","item":"https:\/\/www.comandstyleconseil.com","nextItem":{"@type":"ListItem","@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#listItem","name":"Politique de confidentialit\u00e9"}},{"@type":"ListItem","@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#listItem","position":2,"name":"Politique de confidentialit\u00e9","previousItem":{"@type":"ListItem","@id":"https:\/\/www.comandstyleconseil.com#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.comandstyleconseil.com\/#organization","name":"Com&Style","description":"Mari\u00e8me M. - Conseil en Image & Personal Branding","url":"https:\/\/www.comandstyleconseil.com\/","telephone":"+33675196722","logo":{"@type":"ImageObject","url":"https:\/\/www.comandstyleconseil.com\/wp-content\/uploads\/2023\/09\/logo-def-1.png","@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#organizationLogo","width":1000,"height":1000},"image":{"@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/comandstyle_image\/","https:\/\/www.pinterest.fr\/com_and_style_conseil","https:\/\/www.linkedin.com\/in\/conseilcommunicationetimage"]},{"@type":"WebPage","@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#webpage","url":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/","name":"Politique de confidentialit\u00e9 - Com&Style","description":"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/www.comandstyleconseil.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/#breadcrumblist"},"datePublished":"2023-06-10T14:51:20+02:00","dateModified":"2023-10-18T13:51:53+02:00"},{"@type":"WebSite","@id":"https:\/\/www.comandstyleconseil.com\/#website","url":"https:\/\/www.comandstyleconseil.com\/","name":"Com&Style","description":"Mari\u00e8me M. - Conseil en Image & Personal Branding","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/www.comandstyleconseil.com\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Com&amp;Style - Mari\u00e8me M. - Conseil en Image &amp; Personal Branding","og:type":"article","og:title":"Politique de confidentialit\u00e9 - Com&amp;Style","og:description":"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&amp;Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.","og:url":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/","article:published_time":"2023-06-10T12:51:20+00:00","article:modified_time":"2023-10-18T11:51:53+00:00","twitter:card":"summary_large_image","twitter:title":"Politique de confidentialit\u00e9 - Com&amp;Style","twitter:description":"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&amp;Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com."},"aioseo_meta_data":{"post_id":"3","title":null,"description":"Nous vous demandons de bien vouloir lire attentivement la pr\u00e9sente politique de confidentialit\u00e9 pour comprendre comment sont collect\u00e9es, trait\u00e9es et conserv\u00e9es vos donn\u00e9es personnelles lors de votre utilisation du pr\u00e9sent site internet Com&Style, accessible via l\u2019url https:\/\/www.comandstyleconseil.com.","keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-10-18 13:15:34","updated":"2025-06-04 05:36:26","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.comandstyleconseil.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tPolitique de confidentialit\u00e9\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.comandstyleconseil.com"},{"label":"Politique de confidentialit\u00e9","link":"https:\/\/www.comandstyleconseil.com\/index.php\/politique-de-confidentialite\/"}],"_links":{"self":[{"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":0,"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.comandstyleconseil.com\/index.php\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}